{"id":2033,"date":"2019-05-18T15:19:14","date_gmt":"2019-05-18T15:19:14","guid":{"rendered":""},"modified":"-0001-11-30T00:00:00","modified_gmt":"-0001-11-29T22:00:00","slug":"27943ac3cc8c2a0189507d7623dead6b","status":"publish","type":"post","link":"https:\/\/radioerre.net\/index.php\/2019\/05\/18\/27943ac3cc8c2a0189507d7623dead6b\/","title":{"rendered":"Angelica Sabbatini difende la sua notte rosa."},"content":{"rendered":"<p>\n\t<span style=font-size:14px;><strong>Piena e completa solidariet&agrave; all&rsquo;assessore Sabbatini ed al consigliere Sampaolo insieme al riconoscimento per il loro impegno a favore della riuscita dei tanti eventi programmati.<br \/>\n\tLasciamo che sia la favoletta di Fedro (quella della volpe e l&rsquo;uva) a fare il commento alle dichiarazioni apparse sulla stampa e sui social oggi. Abbiamo accertato che la penale alle societ&agrave; che collaboreranno con il Comune nella realizzazione di &ldquo;Porto Recanati in rosa&rdquo;, nel caso in cui risultino inadempienti rispetto agli impegni assunti, sar&agrave; esattamente pari all&rsquo;impegno economico del Comune.<br \/>\n\tNon merita commento l&rsquo;atteggiamento di una minoranza che si erge a paladina di posizioni esterne senza conoscere la situazione fino in fondo e volto solo a screditare una manifestazione che dovrebbe riguardare tutta la citt&agrave; e tutte le sue componenti.<br \/>\n\tE infine da sempre Porto Recanati ospita una serata di festa l&#39;ultimo sabato di giugno e lo ha deliberato pi&ugrave; di un mese f&agrave;. Casomai altri avrebbero dovuto farla in altra data. Ma questo per qualcuno sarebbe troppo difficile da capire&#8230;&#8230;<\/strong><\/span><\/p>\n<p>;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Piena e completa solidariet&agrave; all&rsquo;assessore Sabbatini ed al consigliere Sampaolo insieme al riconoscimento per il loro impegno a favore della riuscita dei tanti eventi programmati. Lasciamo che sia la favoletta di Fedro (quella della volpe e l&rsquo;uva) a fare il commento alle dichiarazioni apparse sulla stampa e sui social oggi. Abbiamo accertato che la penale &#8230; <a title=\"Angelica Sabbatini difende la sua notte rosa.\" class=\"read-more\" href=\"https:\/\/radioerre.net\/index.php\/2019\/05\/18\/27943ac3cc8c2a0189507d7623dead6b\/\" aria-label=\"Per saperne di pi\u00f9 su Angelica Sabbatini difende la sua notte rosa.\">Leggi tutto<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-2033","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/radioerre.net\/index.php\/wp-json\/wp\/v2\/posts\/2033","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radioerre.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radioerre.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radioerre.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radioerre.net\/index.php\/wp-json\/wp\/v2\/comments?post=2033"}],"version-history":[{"count":1,"href":"https:\/\/radioerre.net\/index.php\/wp-json\/wp\/v2\/posts\/2033\/revisions"}],"predecessor-version":[{"id":16174,"href":"https:\/\/radioerre.net\/index.php\/wp-json\/wp\/v2\/posts\/2033\/revisions\/16174"}],"wp:attachment":[{"href":"https:\/\/radioerre.net\/index.php\/wp-json\/wp\/v2\/media?parent=2033"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radioerre.net\/index.php\/wp-json\/wp\/v2\/categories?post=2033"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radioerre.net\/index.php\/wp-json\/wp\/v2\/tags?post=2033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}