{"id":25296,"date":"2019-05-11T19:19:28","date_gmt":"2019-05-11T19:19:28","guid":{"rendered":""},"modified":"-0001-11-30T00:00:00","modified_gmt":"-0001-11-29T22:00:00","slug":"f0cdc58c3bbabae74e12f9a7a2f6c02f","status":"publish","type":"post","link":"https:\/\/radioerre.net\/index.php\/2019\/05\/11\/f0cdc58c3bbabae74e12f9a7a2f6c02f\/","title":{"rendered":"Una nuova strada per la zona industriale di Villa Musone: promessa del candidato sindaco Antonio Bravi"},"content":{"rendered":"<p>\n\t<span style=font-size:14px;><strong>Attesa da tempo, arriver&agrave; finalmente la nuova strada di collegamento tra la zona industriale Squartabue e la zona Acquaviva di Castelfidardo. Realizzata la parte che ricade sotto la Provincia di Ancona, resta da completare il tratto nel territorio della Provincia di Macerata. Dopo ripetuti tentativi di recuperare in finanziamento necessario, Comune e Regione hanno percorso con successo la strada dei finanziamenti europei per le infrastrutture.&nbsp; &nbsp; &quot;Abbiamo lavorato per cambiare Recanati, continueremo a farlo con la stessa determinazione e concretezza. Vi presentiamo il progetto della nuova viabilit&agrave; nella zona di Villa Musone- ha detto il candidato Sindaco Antonio Bravi incontrando i residenti di Villa Musone-. E&#39; un intervento atteso da residenti, imprenditori e addetti delle varie aziende. La bretella che collega la zona industriale Squartabue alla zona Acquaviva di Castelfidardo &egrave; stata finanziata dalla Regione Marche (800 mila euro, fondi europei) ed il nostro ufficio tecnico sta predisponendo il progetto. Recanati guarda al futuro insieme all&#39;intera vallata del Musone. Ringrazio l&#39;assessore Moreno Pieroni per la collaborazione&quot;. Un collegamento stradale che liberera&#39; Villa Musone dal traffico pesante e dagli ingorghi nelle ore di punta. &quot;La zona industriale dopo anni difficili si sta riqualificando. Abbiamo portato avanti con celerit&agrave; piani di sviluppo per la Pigini, del gruppo Gucci, per la Del Vicario che ora ha acquistato la ex General Music e andr&agrave; a risanare gli immobili. &Egrave; arrivata la Blu Pura e ci sono le aziende storiche- conclude Bravi-. &Egrave; importante che una Amministratore sia al fianco del mondo del lavoro con velocit&agrave; e concretezza&quot;.<\/strong><\/span><\/p>\n<p>;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Attesa da tempo, arriver&agrave; finalmente la nuova strada di collegamento tra la zona industriale Squartabue e la zona Acquaviva di Castelfidardo. Realizzata la parte che ricade sotto la Provincia di Ancona, resta da completare il tratto nel territorio della Provincia di Macerata. Dopo ripetuti tentativi di recuperare in finanziamento necessario, Comune e Regione hanno percorso &#8230; <a title=\"Una nuova strada per la zona industriale di Villa Musone: promessa del candidato sindaco Antonio Bravi\" class=\"read-more\" href=\"https:\/\/radioerre.net\/index.php\/2019\/05\/11\/f0cdc58c3bbabae74e12f9a7a2f6c02f\/\" aria-label=\"Per saperne di pi\u00f9 su Una nuova strada per la zona industriale di Villa Musone: promessa del candidato sindaco Antonio Bravi\">Leggi tutto<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-25296","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/radioerre.net\/index.php\/wp-json\/wp\/v2\/posts\/25296","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radioerre.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radioerre.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radioerre.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radioerre.net\/index.php\/wp-json\/wp\/v2\/comments?post=25296"}],"version-history":[{"count":0,"href":"https:\/\/radioerre.net\/index.php\/wp-json\/wp\/v2\/posts\/25296\/revisions"}],"wp:attachment":[{"href":"https:\/\/radioerre.net\/index.php\/wp-json\/wp\/v2\/media?parent=25296"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radioerre.net\/index.php\/wp-json\/wp\/v2\/categories?post=25296"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radioerre.net\/index.php\/wp-json\/wp\/v2\/tags?post=25296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}